{"id":7266,"date":"2023-10-12T12:48:59","date_gmt":"2023-10-12T11:48:59","guid":{"rendered":"https:\/\/petropompsad.com\/?post_type=product&#038;p=7266"},"modified":"2024-02-20T11:50:23","modified_gmt":"2024-02-20T11:50:23","slug":"ncp-pomps-api-610","status":"publish","type":"product","link":"https:\/\/petropompsad.com\/tr\/urun\/ncp-pomps-api-610\/","title":{"rendered":"NCP POMPS API 610"},"content":{"rendered":"<p style=\"text-align: left;\"><a id=\"product-catalog-bt\" href=\"https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/N_Centrifugal_Pump.pdf\" target=\"_blank\" rel=\"nofollow noopener\">Product Catalog<i class=\"fa fa-file-pdf-o\"><\/i><\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"page\" title=\"Page 2\">\n<table>\n<tbody>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Discharge Flange<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>DN 32 &#8211; DN 500<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Capacity<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>2600 m<sup>3<\/sup>\/h<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Head<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>150 m<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Frequency<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>50 Hz &#8211; 60 Hz<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Temperature of Pumped liquid<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>from &#8211; 25 \u00b0C to + 160 \u00b0C<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Speed<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>1500 rpm\/3000 rpm<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-8304 size-full\" src=\"https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19.webp\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19.webp 800w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19-300x300.webp 300w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19-100x100.webp 100w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19-600x600.webp 600w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19-150x150.webp 150w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19-768x768.webp 768w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/19-12x12.webp 12w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/elementor\/thumbs\/19-qjw6zy28tckk1q355zhl8jd1puodiu2t57en7nsm6w.webp 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>","protected":false},"featured_media":8651,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[263],"product_tag":[],"class_list":["post-7266","product","type-product","status-publish","has-post-thumbnail","product_cat-oil-pumps","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product\/7266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/media\/8651"}],"wp:attachment":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/media?parent=7266"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product_brand?post=7266"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product_cat?post=7266"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product_tag?post=7266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}