{"id":8647,"date":"2024-02-20T11:27:56","date_gmt":"2024-02-20T11:27:56","guid":{"rendered":"https:\/\/petropompsad.com\/?post_type=product&#038;p=8647"},"modified":"2024-02-20T11:30:30","modified_gmt":"2024-02-20T11:30:30","slug":"extra-heavy-duty-slurry-pumps","status":"publish","type":"product","link":"https:\/\/petropompsad.com\/tr\/urun\/extra-heavy-duty-slurry-pumps\/","title":{"rendered":"Extra Heavy Duty Slurry Pumps"},"content":{"rendered":"<p style=\"text-align: left;\"><a id=\"product-catalog-bt\" href=\"https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/Extra_Heavy_Duty Slurry_Pumps.pdf\" target=\"_blank\" rel=\"nofollow noopener\">Product Catalog<i class=\"fa fa-file-pdf-o\"><\/i><\/a><\/p>\n<div class=\"page\" title=\"Page 14\">\n<table>\n<tbody>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Dscharge Flange<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>DN 100 \u2013 DN 250<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Capacty<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>1600 m3\/h<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Head<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>60 m<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Frequency<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>50 Hz \u2013 60 Hz<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Temperature of Pumped lqud<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>from \u2013 25 \u00b0C to + 160 \u00b0C<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Speed<\/p>\n<\/div>\n<\/div>\n<\/td>\n<td>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>1500 rpm<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-8151 size-full\" src=\"https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95.webp\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95.webp 800w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95-300x300.webp 300w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95-100x100.webp 100w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95-600x600.webp 600w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95-150x150.webp 150w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95-768x768.webp 768w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/95-12x12.webp 12w, https:\/\/petropompsad.com\/wp-content\/uploads\/2024\/02\/elementor\/thumbs\/95-qjvvf5gkd00dydi5ybo047pz4305egfku9irfns388.webp 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>","protected":false},"featured_media":8648,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[264],"product_tag":[],"class_list":["post-8647","product","type-product","status-publish","has-post-thumbnail","product_cat-water-pumps","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product\/8647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/media\/8648"}],"wp:attachment":[{"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/media?parent=8647"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product_brand?post=8647"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product_cat?post=8647"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/petropompsad.com\/tr\/wp-json\/wp\/v2\/product_tag?post=8647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}